{"id":27592,"date":"2023-09-24T09:10:23","date_gmt":"2023-09-24T13:10:23","guid":{"rendered":"https:\/\/damasketdentelle.com\/?p=27592"},"modified":"2023-09-24T09:10:23","modified_gmt":"2023-09-24T13:10:23","slug":"design-her-may-morris","status":"publish","type":"post","link":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/","title":{"rendered":"Design.HER: May Morris"},"content":{"rendered":"<div id=\"attachment_27593\" style=\"width: 705px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27593\" class=\"wp-image-27593 size-large\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/Screenshot-2023-09-16-at-12.58.04-PM-695x794.jpg\" alt=\"\" width=\"695\" height=\"794\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/Screenshot-2023-09-16-at-12.58.04-PM-695x794.jpg 695w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/Screenshot-2023-09-16-at-12.58.04-PM-394x450.jpg 394w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/Screenshot-2023-09-16-at-12.58.04-PM-768x878.jpg 768w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/Screenshot-2023-09-16-at-12.58.04-PM.jpg 1092w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><p id=\"caption-attachment-27593\" class=\"wp-caption-text\">Dante Gabriel Rossetti, \u201cPortrait of May Morris,\u201d 1871, coloured chalks on pale blue-gray paper, 43.8 \u00d7 39.3 cm, Society of Antiquaries of London, Kelmscott Manor.<\/p><\/div>\n<p>Linda Parry, dans son livre <a href=\"https:\/\/bit.ly\/46opwod\"><strong>William Morris Textiles<\/strong><\/a>, \u00e9crit : &#8220;Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l&#8217;ombre de son p\u00e8re. Son choix de travailler avec les m\u00eames techniques et les m\u00eames mani\u00e8res de concevoir rend difficile de juger son travail objectivement sans se r\u00e9f\u00e9rer constamment \u00e0 l&#8217;\u0153uvre de William Morris&#8221;.<\/p>\n<p>N\u00e9e en 1862, au moment o\u00f9 son p\u00e8re lan\u00e7ait l&#8217;entreprise qui allait devenir Morris &amp; Co, May Morris \u00e9tait la fille de William et Jane Morris, la c\u00e9l\u00e8bre mod\u00e8le des peintres pr\u00e9rapha\u00e9lites. Elle a grandi dans le monde de l&#8217;Arts and Crafts et des pr\u00e9rapha\u00e9lites, visitant les ateliers de Morris &amp; Co. avec son p\u00e8re et posant pour des artistes tels que Dante Gabriel Rossetti et Edward Burne-Jones. Sa m\u00e8re et sa tante lui enseignent la broderie, pour laquelle elle fait preuve d&#8217;un talent pr\u00e9coce, et l&#8217;encouragent \u00e0 cr\u00e9er ses propres motifs.<\/p>\n<div id=\"attachment_27599\" style=\"width: 425px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27599\" class=\"wp-image-27599 size-full\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_Hollyer_photo_2990b6bae359febd2d8c25c07e982dea.jpg\" alt=\"\" width=\"415\" height=\"600\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_Hollyer_photo_2990b6bae359febd2d8c25c07e982dea.jpg 415w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_Hollyer_photo_2990b6bae359febd2d8c25c07e982dea-311x450.jpg 311w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/><p id=\"caption-attachment-27599\" class=\"wp-caption-text\">Photograph of May Morris by Frederick Hollyer, ca. 1890. Museum no. 7821-1938. \u00a9 Victoria &amp; Albert Museum.<\/p><\/div>\n<p>Apr\u00e8s avoir \u00e9tudi\u00e9 les arts textiles \u00e0 la South Kensington School of Design, elle a pris en charge la section broderie de Morris &amp; Co. en 1885, \u00e0 l&#8217;\u00e2ge de 23 ans seulement, et a assum\u00e9 la responsabilit\u00e9 de tous les nouveaux motifs ainsi que l&#8217;ex\u00e9cution des commandes plus importantes et plus complexes telles que les tentures murales, les nappes d&#8217;autel et les tapisseries. Ses cr\u00e9ations s&#8217;inscrivent dans l&#8217;esth\u00e9tique Arts and Crafts, avec des formes naturelles stylis\u00e9es, des lignes fluides et des influences de l&#8217;art m\u00e9di\u00e9val, et elles utilisent des points directionnels pour ajouter de la texture et donner une impression de mouvement. Il s&#8217;agissait de la broderie en tant qu&#8217;art, \u00e9lev\u00e9e au-dessus de son contexte domestique normal.<\/p>\n<p>May Morris \u00e9tait un socialiste convaincu et a contribu\u00e9 \u00e0 la fondation de la Women&#8217;s Guild of Arts en 1907. Cette organisation a \u00e9t\u00e9 cr\u00e9\u00e9e pour soutenir les femmes travaillant dans le domaine des arts et de l&#8217;artisanat, \u00e0 une \u00e9poque o\u00f9 elles \u00e9taient exclues d&#8217;autres organisations similaires (comme l&#8217;Art Workers&#8217; Guild, qui n&#8217;a admis les femmes qu&#8217;en 1972). May \u00e9tait \u00e9galement une r\u00e9dactrice exp\u00e9riment\u00e9e, qui a pass\u00e9 ses derni\u00e8res ann\u00e9es \u00e0 \u00e9diter les 24 volumes de l&#8217;\u0153uvre de son p\u00e8re.<\/p>\n<div id=\"attachment_27600\" style=\"width: 455px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27600\" class=\"wp-image-27600 size-full\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_embroidery_design_051660437839ffe88b219c1c81e58042.jpg\" alt=\"\" width=\"445\" height=\"600\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_embroidery_design_051660437839ffe88b219c1c81e58042.jpg 445w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_embroidery_design_051660437839ffe88b219c1c81e58042-334x450.jpg 334w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><p id=\"caption-attachment-27600\" class=\"wp-caption-text\">Embroidery design by May Morris, ca. 1885. Museum no. E.50-1940. \u00a9 Victoria &amp; Albert Museum<\/p><\/div>\n<p>Une grande partie du succ\u00e8s de la broderie Morris &amp; Co. \u00e0 la fin du XIXe si\u00e8cle et au d\u00e9but du XXe si\u00e8cle doit \u00eatre attribu\u00e9e au travail acharn\u00e9 de May, qui concevait, brodait et supervisait le travail, d&#8217;abord dans l&#8217;atelier de Hammersmith Terrace, puis au 449 Oxford Street et, pendant quelques ann\u00e9es, \u00e0 Kelmscott Manor.<\/p>\n<div id=\"attachment_27596\" style=\"width: 705px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27596\" class=\"wp-image-27596 size-large\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033-695x847.webp\" alt=\"\" width=\"695\" height=\"847\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033-695x847.webp 695w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033-369x450.webp 369w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033-768x936.webp 768w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033-1260x1536.webp 1260w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-033.webp 1600w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><p id=\"caption-attachment-27596\" class=\"wp-caption-text\">Kelmscott Manor, avec une toile de May Morris au dessus de la cr\u00e9dence. Architectural Digest<\/p><\/div>\n<p>Les papiers peints et les textiles d\u00e9cor\u00e9s d&#8217;ornements floraux sont caract\u00e9ristiques des produits associ\u00e9s \u00e0 la soci\u00e9t\u00e9 de William Morris. Bien que le papier peint Horn Poppy ait \u00e9t\u00e9 r\u00e9alis\u00e9 par sa fille May Morris, l&#8217;impression est l&#8217;un des motifs qui ont parfois \u00e9t\u00e9 faussement attribu\u00e9s \u00e0 Morris lui-m\u00eame. De nombreuses \u0153uvres de May ont \u00e9t\u00e9 inspir\u00e9es par son p\u00e8re et ses po\u00e8mes, tout comme ce papier peint sp\u00e9cifique. Dans l&#8217;un de ses po\u00e8mes, William Morris qualifie le pavot cornu de &#8221; fin et brillant &#8220;, ce qui a pu influencer la repr\u00e9sentation de la plante par May.<\/p>\n<div id=\"attachment_27601\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27601\" class=\"wp-image-27601 size-full\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_wallpaper_78e0f54e529738d9ebf28b4d31a1c919.jpg\" alt=\"\" width=\"515\" height=\"585\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_wallpaper_78e0f54e529738d9ebf28b4d31a1c919.jpg 515w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/May_Morris_wallpaper_78e0f54e529738d9ebf28b4d31a1c919-396x450.jpg 396w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><p id=\"caption-attachment-27601\" class=\"wp-caption-text\">\u2018Honeysuckle\u2019 wallpaper, designed by May Morris, ca. 1883. Museum no. E. 668-1915. \u00a9 Victoria &amp; Albert Museum<\/p><\/div>\n<p>May Morris a \u00e9galement cr\u00e9\u00e9 des bijoux et des papiers peints, dont le magnifique motif du ch\u00e8vrefeuille, dans lequel elle fait preuve d&#8217;un flair pour traduire les formes naturelles en motifs r\u00e9p\u00e9titifs qui correspond \u00e0 celui de son p\u00e8re. Apr\u00e8s la mort de William, elle quitta l&#8217;entreprise, tout en restant conseill\u00e8re, et devint une avocate passionn\u00e9e de l&#8217;artisanat et en particulier de la broderie. Elle \u00e9crivit des articles et un livre, enseigna \u00e0 la Central School of Arts and Crafts, entreprit une tourn\u00e9e de conf\u00e9rences en Am\u00e9rique et cofonda la Women&#8217;s Guild of Arts (Guilde des femmes pour les arts).<\/p>\n<div id=\"attachment_27595\" style=\"width: 705px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27595\" class=\"wp-image-27595 size-large\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-695x1043.webp\" alt=\"\" width=\"695\" height=\"1043\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-695x1043.webp 695w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-300x450.webp 300w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-768x1152.webp 768w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-1024x1536.webp 1024w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047-1365x2048.webp 1365w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-047.webp 1600w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><p id=\"caption-attachment-27595\" class=\"wp-caption-text\">Kelmscott Manor est un manoir des XVIe et XVIIe si\u00e8cles situ\u00e9 dans le village de Kelmscott, dans l&#8217;Oxfordshire. William Morris a lou\u00e9 la maison en 1871. Jane Morris acheta la maison en 1913. Elle le l\u00e9gua ensuite \u00e0 May, qui y r\u00e9sida toute l&#8217;ann\u00e9e, des ann\u00e9es 1920 jusqu&#8217;\u00e0 sa mort en 1938. Elle a l\u00e9gu\u00e9 la maison \u00e0 l&#8217;Universit\u00e9 d&#8217;Oxford, qui l&#8217;a transmise \u00e0 la Society of Antiquaries, qui la g\u00e8re aujourd&#8217;hui.<\/p><\/div>\n<h2>Parmi les contributions notables du Mouvement Arts &amp; Crafts<\/h2>\n<p><strong>L&#8217;utilisation de mat\u00e9riaux naturels<\/strong> : Le ch\u00eane, le cerisier et d&#8217;autres mat\u00e9riaux naturels \u00e9taient privil\u00e9gi\u00e9s pour le mobilier et la d\u00e9coration.<\/p>\n<p><strong>Formes simples et design fonctionnel : <\/strong>Les meubles sont con\u00e7us pour \u00eatre fonctionnels, avec des lignes \u00e9pur\u00e9es et une attention particuli\u00e8re port\u00e9e \u00e0 l&#8217;artisanat.<\/p>\n<p><strong>Vitraux<\/strong> : Les vitraux deviennent populaires dans les maisons et les b\u00e2timents publics, ajoutant une touche artistique.<\/p>\n<p><strong>Textiles et papiers peints<\/strong> : Les textiles brod\u00e9s et les papiers peints \u00e9labor\u00e9s, avec des motifs inspir\u00e9s de la nature et des dessins faits \u00e0 la main, sont tr\u00e8s r\u00e9pandus.<\/p>\n<p><strong>L&#8217;art de l&#8217;artisanat<\/strong> : En tant que figure \u00e9minente du mouvement Arts &amp; Crafts, un mouvement qui c\u00e9l\u00e9brait la valeur des cr\u00e9ations artisanales faites \u00e0 la main. Son d\u00e9vouement \u00e0 la cr\u00e9ation de textiles et de broderies complexes \u00e0 la main illustre le principe fondamental du DIY, qui consiste \u00e0 fabriquer des articles personnellement et m\u00e9ticuleusement.<\/p>\n<p><strong>L&#8217;accent mis sur la cr\u00e9ativit\u00e9 individuelle<\/strong> : Dans son travail, May Morris a donn\u00e9 la priorit\u00e9 \u00e0 la cr\u00e9ativit\u00e9 et \u00e0 l&#8217;expression individuelles. Elle encourageait les artistes et les artisans \u00e0 explorer leurs talents et leurs styles uniques, ce qui correspond \u00e0 l&#8217;\u00e9thique DIY de l&#8217;expression personnelle et de l&#8217;individualisme.<\/p>\n<p><strong>R\u00e9action \u00e0 l&#8217;industrialisation<\/strong> : Le mouvement Arts &amp; Crafts, auquel appartenait May Morris, est n\u00e9 en r\u00e9action aux effets d\u00e9shumanisants de l&#8217;industrialisation et de la production de masse. Ce mouvement a cherch\u00e9 \u00e0 restaurer le sens de l&#8217;artisanat et la fiert\u00e9 de son travail, un aspect cl\u00e9 du rejet des produits de masse par la culture DIY.<\/p>\n<p><strong>Enseignement et partage des comp\u00e9tences<\/strong> : May Morris s&#8217;est \u00e9galement impliqu\u00e9e dans l&#8217;enseignement et le partage de ses comp\u00e9tences en mati\u00e8re de broderie et de design. Cet aspect \u00e9ducatif est une composante fondamentale de la culture DIY, qui implique souvent que les individus transmettent leurs connaissances et leurs comp\u00e9tences \u00e0 d&#8217;autres dans le cadre d&#8217;une communaut\u00e9.<\/p>\n<p><strong>Durabilit\u00e9 et production \u00e9thique<\/strong> : L&#8217;accent mis par May Morris sur la cr\u00e9ation de pi\u00e8ces belles, fonctionnelles et durables refl\u00e8te un engagement en faveur de la durabilit\u00e9 et de la production \u00e9thique, des valeurs qui r\u00e9sonnent avec l&#8217;accent mis par la culture DIY contemporaine sur l&#8217;artisanat responsable et attentif.<\/p>\n<div id=\"attachment_27594\" style=\"width: 705px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27594\" class=\"wp-image-27594 size-large\" src=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-695x1043.webp\" alt=\"\" width=\"695\" height=\"1043\" srcset=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-695x1043.webp 695w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-300x450.webp 300w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-768x1152.webp 768w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-1024x1536.webp 1024w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069-1365x2048.webp 1365w, https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp 1600w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><p id=\"caption-attachment-27594\" class=\"wp-caption-text\">Kelmscott Manor, Architectural Digest<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Linda Parry, dans son livre William Morris Textiles, \u00e9crit : &#8220;Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l&#8217;ombre de son p\u00e8re. Son choix de travailler avec les m\u00eames techniques et les m\u00eames mani\u00e8res de concevoir rend difficile de juger son travail objectivement sans se r\u00e9f\u00e9rer&#8230;<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":27594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[4510,3432],"tags":[4513,4512,2968,4511,4482],"class_list":{"0":"post-27592","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-design-her","8":"category-francais","9":"tag-arts-and-crafts-movement","10":"tag-design-her","11":"tag-featured","12":"tag-may-morris","13":"tag-william-morris","14":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Design.HER: May Morris - Interior design ideas | Home decor blog<\/title>\n<meta name=\"description\" content=\"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l&#039;ombre de son p\u00e8re, William Morris.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design.HER: May Morris - Interior design ideas | Home decor blog\" \/>\n<meta property=\"og:description\" content=\"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l&#039;ombre de son p\u00e8re, William Morris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/\" \/>\n<meta property=\"og:site_name\" content=\"Damask &amp; Dentelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/damasketdentelle\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T13:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"2401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Vanessa Sicotte\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanessa Sicotte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/\"},\"author\":{\"name\":\"Vanessa Sicotte\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/#\\\/schema\\\/person\\\/ab66dcd0f6a0e1954b4a4aaac173acee\"},\"headline\":\"Design.HER: May Morris\",\"datePublished\":\"2023-09-24T13:10:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/\"},\"wordCount\":1247,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.damasketdentelle.com\\\/wp-content\\\/uploads\\\/WM-069.webp\",\"keywords\":[\"Arts and Crafts Movement\",\"Design.HER\",\"featured\",\"May Morris\",\"William Morris\"],\"articleSection\":[\"Design.HER\",\"Fran\u00e7ais\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/\",\"url\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/\",\"name\":\"Design.HER: May Morris - Interior design ideas | Home decor blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.damasketdentelle.com\\\/wp-content\\\/uploads\\\/WM-069.webp\",\"datePublished\":\"2023-09-24T13:10:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/#\\\/schema\\\/person\\\/ab66dcd0f6a0e1954b4a4aaac173acee\"},\"description\":\"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l'ombre de son p\u00e8re, William Morris.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.damasketdentelle.com\\\/wp-content\\\/uploads\\\/WM-069.webp\",\"contentUrl\":\"https:\\\/\\\/blog.damasketdentelle.com\\\/wp-content\\\/uploads\\\/WM-069.webp\",\"width\":1600,\"height\":2401,\"caption\":\"Kelmscott Manor, Architectural Digest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/2023\\\/09\\\/design-her-may-morris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/damasketdentelle.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Design.HER: May Morris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/#website\",\"url\":\"https:\\\/\\\/damasketdentelle.com\\\/\",\"name\":\"Damask &amp; Dentelle\",\"description\":\"Storytelling, Design and urban manifestos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/damasketdentelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/damasketdentelle.com\\\/#\\\/schema\\\/person\\\/ab66dcd0f6a0e1954b4a4aaac173acee\",\"name\":\"Vanessa Sicotte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g\",\"caption\":\"Vanessa Sicotte\"},\"sameAs\":[\"https:\\\/\\\/blog.damasketdentelle.com\\\/wp-login.php\"],\"url\":\"https:\\\/\\\/damasketdentelle.com\\\/index.php\\\/author\\\/vanessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Design.HER: May Morris - Interior design ideas | Home decor blog","description":"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l'ombre de son p\u00e8re, William Morris.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/","og_locale":"en_US","og_type":"article","og_title":"Design.HER: May Morris - Interior design ideas | Home decor blog","og_description":"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l'ombre de son p\u00e8re, William Morris.","og_url":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/","og_site_name":"Damask &amp; Dentelle","article_publisher":"https:\/\/www.facebook.com\/damasketdentelle","article_published_time":"2023-09-24T13:10:23+00:00","og_image":[{"width":1600,"height":2401,"url":"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp","type":"image\/webp"}],"author":"Vanessa Sicotte","twitter_misc":{"Written by":"Vanessa Sicotte","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#article","isPartOf":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/"},"author":{"name":"Vanessa Sicotte","@id":"https:\/\/damasketdentelle.com\/#\/schema\/person\/ab66dcd0f6a0e1954b4a4aaac173acee"},"headline":"Design.HER: May Morris","datePublished":"2023-09-24T13:10:23+00:00","mainEntityOfPage":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/"},"wordCount":1247,"commentCount":0,"image":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp","keywords":["Arts and Crafts Movement","Design.HER","featured","May Morris","William Morris"],"articleSection":["Design.HER","Fran\u00e7ais"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/","url":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/","name":"Design.HER: May Morris - Interior design ideas | Home decor blog","isPartOf":{"@id":"https:\/\/damasketdentelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#primaryimage"},"image":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp","datePublished":"2023-09-24T13:10:23+00:00","author":{"@id":"https:\/\/damasketdentelle.com\/#\/schema\/person\/ab66dcd0f6a0e1954b4a4aaac173acee"},"description":"Les talents de May Morris ont longtemps \u00e9t\u00e9 sous-estim\u00e9s et elle a, pendant trop longtemps, v\u00e9cu dans l'ombre de son p\u00e8re, William Morris.","breadcrumb":{"@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#primaryimage","url":"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp","contentUrl":"https:\/\/blog.damasketdentelle.com\/wp-content\/uploads\/WM-069.webp","width":1600,"height":2401,"caption":"Kelmscott Manor, Architectural Digest"},{"@type":"BreadcrumbList","@id":"https:\/\/damasketdentelle.com\/index.php\/2023\/09\/design-her-may-morris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/damasketdentelle.com\/"},{"@type":"ListItem","position":2,"name":"Design.HER: May Morris"}]},{"@type":"WebSite","@id":"https:\/\/damasketdentelle.com\/#website","url":"https:\/\/damasketdentelle.com\/","name":"Damask &amp; Dentelle","description":"Storytelling, Design and urban manifestos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/damasketdentelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/damasketdentelle.com\/#\/schema\/person\/ab66dcd0f6a0e1954b4a4aaac173acee","name":"Vanessa Sicotte","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7710c0e6cd087dff617e494d4e51105fae871a738d48c9031273d8920420be5b?s=96&d=mm&r=g","caption":"Vanessa Sicotte"},"sameAs":["https:\/\/blog.damasketdentelle.com\/wp-login.php"],"url":"https:\/\/damasketdentelle.com\/index.php\/author\/vanessa\/"}]}},"_links":{"self":[{"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/posts\/27592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/comments?post=27592"}],"version-history":[{"count":1,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/posts\/27592\/revisions"}],"predecessor-version":[{"id":27602,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/posts\/27592\/revisions\/27602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/media\/27594"}],"wp:attachment":[{"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/media?parent=27592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/categories?post=27592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damasketdentelle.com\/index.php\/wp-json\/wp\/v2\/tags?post=27592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}